{"id":10168,"date":"2020-05-01T15:27:24","date_gmt":"2020-05-01T19:27:24","guid":{"rendered":"https:\/\/fireflyin.org\/?p=10168"},"modified":"2025-02-25T12:06:51","modified_gmt":"2025-02-25T17:06:51","slug":"is-it-punishment-or-discipline","status":"publish","type":"post","link":"https:\/\/fireflyin.org\/fr\/resources\/news-library\/is-it-punishment-or-discipline\/","title":{"rendered":"EST-CE UNE PUNITION OU UNE DISCIPLINE\u00a0?"},"content":{"rendered":"<p>Auteur : Ren\u00e9 Elsbury ; MSW, LSW<br \/>\nTh\u00e9rapeute \u00e0 domicile<\/p>\n<p>&nbsp;<\/p>\n<p>Quand j&#039;entends le mot punition, je pense \u00e0 quand j&#039;\u00e9tais petite fille et que je devais nettoyer ma chambre par une journ\u00e9e ensoleill\u00e9e ; J&#039;avais l&#039;impression que mes parents me d\u00e9testaient parce qu&#039;ils ne me laissaient pas jouer avec mes amis. Je me souviens aussi des disputes que j&#039;ai eues avec mes parents \u00e0 propos des couvre-feux au lyc\u00e9e. C&#039;\u00e9tait tellement injuste que mes amis n&#039;aient pas \u00e0 \u00eatre \u00e0 la maison aussi t\u00f4t que moi. Quand je repense \u00e0 mon enfance, je ne pense pas aux fess\u00e9es que j&#039;ai re\u00e7ues car elles \u00e9taient rares, ni \u00e0 me laver la bouche avec du savon pour avoir trait\u00e9 mon p\u00e8re d&#039;une mauvaise r\u00e9putation. Peut-\u00eatre \u00e9tait-ce parce que je sentais que je m\u00e9ritais davantage les punitions quand j&#039;ai compris que ce que je faisais \u00e9tait mal, plut\u00f4t qu&#039;une simple fess\u00e9e rapide sans aucune explication.<\/p>\n<p>En tant que parent, mon point de vue a chang\u00e9 en mati\u00e8re de punition et de discipline. Ce qui semblait \u00eatre des cons\u00e9quences horribles en tant qu&#039;enfant n&#039;\u00e9tait que de la discipline. Mes parents fixaient des limites pour m&#039;apprendre \u00e0 \u00eatre responsable, \u00e0 rendre des comptes et, surtout, \u00e0 me prot\u00e9ger. Je fais la m\u00eame chose avec mes enfants aujourd&#039;hui; mon approche est juste un peu diff\u00e9rente. Je discipline mes enfants en fixant des limites. Je veux que mes enfants soient \u00e0 l&#039;abri du mal et je veux qu&#039;ils apprennent \u00e0 \u00eatre des adultes responsables et qu&#039;ils acqui\u00e8rent les comp\u00e9tences de vie dont ils auront besoin pour fonctionner en tant qu&#039;adultes. Je veux les m\u00eames choses pour mes enfants que mes parents voulaient pour moi et maintenant je comprends plus que jamais leur point de vue. J&#039;ai donc \u00e9tabli des couvre-feux et \u00e9tabli des r\u00e8gles claires concernant l&#039;utilisation d&#039;Internet et du t\u00e9l\u00e9phone. Mes enfants ont des corv\u00e9es adapt\u00e9es \u00e0 leur \u00e2ge qu&#039;ils doivent accomplir chaque semaine et lorsqu&#039;ils ne font pas leurs corv\u00e9es, leurs privil\u00e8ges leur sont retir\u00e9s. Je suis s\u00fbr qu&#039;ils ont l&#039;impression que je suis une m\u00e8re m\u00e9chante et que je les punis, mais en r\u00e9alit\u00e9, j&#039;utilise simplement des techniques de discipline que je sais efficaces.<\/p>\n<p>Pourquoi est-ce que je ne donne pas la fess\u00e9e, ne tape pas, ne crie pas, ne verrouille pas les portes des chambres et n&#039;utilise pas de savon\u00a0? Ce n&#039;est pas parce que je suis th\u00e9rapeute \u2013 j&#039;ai \u00e9t\u00e9 parent pendant de nombreuses ann\u00e9es avant de devenir th\u00e9rapeute. Cependant, devenir th\u00e9rapeute m&#039;a permis de mieux comprendre pourquoi la punition n&#039;est pas une forme efficace de discipline. Je ne punis pas mes enfants parce que ce n&#039;est pas ce qui m&#039;a appris les le\u00e7ons d&#039;une vie d&#039;enfant. C&#039;\u00e9tait la discipline et la structure que mes parents fournissaient : routines du coucher, heures fixes des repas, devoirs et r\u00e9cr\u00e9ation. C&#039;\u00e9tait l&#039;organisation de savoir \u00e0 quoi s&#039;attendre jour apr\u00e8s jour. C&#039;\u00e9tait avoir des privil\u00e8ges comme jouer avec des amis, profiter de sucettes glac\u00e9es et regarder mon \u00e9mission de t\u00e9l\u00e9vision pr\u00e9f\u00e9r\u00e9e \u00eatre supprim\u00e9e lorsque je ne suivais pas les r\u00e8gles de la maison. Ce sont les mesures de s\u00e9curit\u00e9 et les couvre-feux, le fait de devoir parler aux parents d&#039;amis avec qui je voulais jouer et de devoir porter un casque lors des balades \u00e0 v\u00e9lo qui m&#039;ont aid\u00e9 \u00e0 devenir un adulte capable et responsable. Il s&#039;agissait d&#039;avoir les r\u00e8gles et les attentes clairement \u00e9nonc\u00e9es pour moi en tant qu&#039;enfant et pas seulement d&#039;\u00eatre maquill\u00e9es sur place. Il expliquait la raison derri\u00e8re la discipline alors que je ne comprenais pas la r\u00e8gle. Ce sont les choses qui m&#039;ont appris les le\u00e7ons dont j&#039;avais besoin pour arriver l\u00e0 o\u00f9 je suis aujourd&#039;hui.<\/p>\n<p>J&#039;esp\u00e8re qu&#039;un jour mes enfants regarderont en arri\u00e8re et se souviendront que je les aimais. J&#039;esp\u00e8re qu&#039;ils savent que j&#039;ai fait de mon mieux pour les prot\u00e9ger et apprendre \u00e0 r\u00e9ussir dans la vie en leur apprenant ce dont ils auraient besoin pour leur avenir. Je suis reconnaissant d&#039;avoir appris ces dures le\u00e7ons de vie avec amour et soutien et d&#039;avoir pu prouver qu&#039;on pouvait me faire confiance pour faire de bons choix. J&#039;esp\u00e8re que mes enfants l&#039;apprendront aussi. En fin de compte, je veux ce que tous les parents veulent : je veux que mes enfants soient en bonne sant\u00e9, heureux et en s\u00e9curit\u00e9.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Quand j&#039;entends le mot punition, je pense \u00e0 quand j&#039;\u00e9tais petite fille et que je devais nettoyer ma chambre par une journ\u00e9e ensoleill\u00e9e ; J&#039;avais l&#039;impression que mes parents me d\u00e9testaient parce qu&#039;ils ne me laissaient pas jouer avec mes amis. Je me souviens aussi des disputes que j&#039;ai eues avec mes parents \u00e0 propos des couvre-feux au lyc\u00e9e. C&#039;\u00e9tait tellement injuste que mes amis n&#039;aient pas \u00e0 \u00eatre \u00e0 la maison aussi t\u00f4t que moi. Quand je repense \u00e0 mon enfance, je ne pense pas aux fess\u00e9es que j&#039;ai re\u00e7ues car elles \u00e9taient rares, ni \u00e0 me laver la bouche avec du savon pour avoir trait\u00e9 mon p\u00e8re d&#039;une mauvaise r\u00e9putation. Peut-\u00eatre \u00e9tait-ce parce que je sentais que je m\u00e9ritais davantage les punitions quand j&#039;ai compris que ce que je faisais \u00e9tait mal, plut\u00f4t qu&#039;une simple fess\u00e9e rapide sans aucune explication.<\/p>","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-10168","post","type-post","status-publish","format-standard","hentry","category-family-childhood-development"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IS IT PUNISHMENT, OR DISCIPLINE? - Firefly Children and Family Alliance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fireflyin.org\/fr\/resources\/news-library\/is-it-punishment-or-discipline\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IS IT PUNISHMENT, OR DISCIPLINE? - Firefly Children and Family Alliance\" \/>\n<meta property=\"og:description\" content=\"When I hear the word punishment I think about when I was a little girl and having to clean my room on a sunny day; I felt like my parents hated me because they didn\u2019t let me play with my friends. I also remember the arguments I had with my parents about curfews in high school. It felt so unfair when my friends didn\u2019t have to be home as early as I did. When I reflect on my childhood, I don\u2019t think about the spankings that I received as they were far and few between, or getting my mouth washed out with soap for calling my Dad a bad name. Maybe it was because I felt I deserved the punishments more when I understood what I was doing was wrong, rather than just a quick spanking without any explanation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fireflyin.org\/fr\/resources\/news-library\/is-it-punishment-or-discipline\/\" \/>\n<meta property=\"og:site_name\" content=\"Firefly Children and Family Alliance\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-01T19:27:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T17:06:51+00:00\" \/>\n<meta name=\"author\" content=\"Firefly Children and Family Alliance\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Firefly Children and Family Alliance\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fireflyin.org\\\/resources\\\/news-library\\\/is-it-punishment-or-discipline\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fireflyin.org\\\/resources\\\/news-library\\\/is-it-punishment-or-discipline\\\/\"},\"author\":{\"name\":\"Firefly Children and Family Alliance\",\"@id\":\"https:\\\/\\\/fireflyin.org\\\/#\\\/schema\\\/person\\\/4a0a717d05ab7bca77c74ce89ec295bf\"},\"headline\":\"IS IT PUNISHMENT, OR DISCIPLINE?\",\"datePublished\":\"2020-05-01T19:27:24+00:00\",\"dateModified\":\"2025-02-25T17:06:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fireflyin.org\\\/resources\\\/news-library\\\/is-it-punishment-or-discipline\\\/\"},\"wordCount\":672,\"commentCount\":0,\"articleSection\":[\"Family &amp; Childhood Development\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fireflyin.org\\\/resources\\\/news-library\\\/is-it-punishment-or-discipline\\\/\",\"url\":\"https:\\\/\\\/fireflyin.org\\\/resources\\\/news-library\\\/is-it-punishment-or-discipline\\\/\",\"name\":\"IS IT PUNISHMENT, OR DISCIPLINE? - Firefly Children and Family Alliance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fireflyin.org\\\/#website\"},\"datePublished\":\"2020-05-01T19:27:24+00:00\",\"dateModified\":\"2025-02-25T17:06:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/fireflyin.org\\\/#\\\/schema\\\/person\\\/4a0a717d05ab7bca77c74ce89ec295bf\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fireflyin.org\\\/resources\\\/news-library\\\/is-it-punishment-or-discipline\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fireflyin.org\\\/resources\\\/news-library\\\/is-it-punishment-or-discipline\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fireflyin.org\\\/resources\\\/news-library\\\/is-it-punishment-or-discipline\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fireflyin.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IS IT PUNISHMENT, OR DISCIPLINE?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fireflyin.org\\\/#website\",\"url\":\"https:\\\/\\\/fireflyin.org\\\/\",\"name\":\"Firefly Children and Family Alliance\",\"description\":\"foster parents impact, foster kids, foster parents needed, a foster parent&#039;s role\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fireflyin.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fireflyin.org\\\/#\\\/schema\\\/person\\\/4a0a717d05ab7bca77c74ce89ec295bf\",\"name\":\"Firefly Children and Family Alliance\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05d76712c41f02a8e2d8f22346b1a85e7f00cb4436efc2fa6670ee39129fd71b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05d76712c41f02a8e2d8f22346b1a85e7f00cb4436efc2fa6670ee39129fd71b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05d76712c41f02a8e2d8f22346b1a85e7f00cb4436efc2fa6670ee39129fd71b?s=96&d=mm&r=g\",\"caption\":\"Firefly Children and Family Alliance\"},\"url\":\"https:\\\/\\\/fireflyin.org\\\/fr\\\/resources\\\/news-library\\\/author\\\/firefly-children-and-family-alliance\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IS IT PUNISHMENT, OR DISCIPLINE? - Firefly Children and Family Alliance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fireflyin.org\/fr\/resources\/news-library\/is-it-punishment-or-discipline\/","og_locale":"fr_FR","og_type":"article","og_title":"IS IT PUNISHMENT, OR DISCIPLINE? - Firefly Children and Family Alliance","og_description":"When I hear the word punishment I think about when I was a little girl and having to clean my room on a sunny day; I felt like my parents hated me because they didn\u2019t let me play with my friends. I also remember the arguments I had with my parents about curfews in high school. It felt so unfair when my friends didn\u2019t have to be home as early as I did. When I reflect on my childhood, I don\u2019t think about the spankings that I received as they were far and few between, or getting my mouth washed out with soap for calling my Dad a bad name. Maybe it was because I felt I deserved the punishments more when I understood what I was doing was wrong, rather than just a quick spanking without any explanation.","og_url":"https:\/\/fireflyin.org\/fr\/resources\/news-library\/is-it-punishment-or-discipline\/","og_site_name":"Firefly Children and Family Alliance","article_published_time":"2020-05-01T19:27:24+00:00","article_modified_time":"2025-02-25T17:06:51+00:00","author":"Firefly Children and Family Alliance","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Firefly Children and Family Alliance","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fireflyin.org\/resources\/news-library\/is-it-punishment-or-discipline\/#article","isPartOf":{"@id":"https:\/\/fireflyin.org\/resources\/news-library\/is-it-punishment-or-discipline\/"},"author":{"name":"Firefly Children and Family Alliance","@id":"https:\/\/fireflyin.org\/#\/schema\/person\/4a0a717d05ab7bca77c74ce89ec295bf"},"headline":"IS IT PUNISHMENT, OR DISCIPLINE?","datePublished":"2020-05-01T19:27:24+00:00","dateModified":"2025-02-25T17:06:51+00:00","mainEntityOfPage":{"@id":"https:\/\/fireflyin.org\/resources\/news-library\/is-it-punishment-or-discipline\/"},"wordCount":672,"commentCount":0,"articleSection":["Family &amp; Childhood Development"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/fireflyin.org\/resources\/news-library\/is-it-punishment-or-discipline\/","url":"https:\/\/fireflyin.org\/resources\/news-library\/is-it-punishment-or-discipline\/","name":"IS IT PUNISHMENT, OR DISCIPLINE? - Firefly Children and Family Alliance","isPartOf":{"@id":"https:\/\/fireflyin.org\/#website"},"datePublished":"2020-05-01T19:27:24+00:00","dateModified":"2025-02-25T17:06:51+00:00","author":{"@id":"https:\/\/fireflyin.org\/#\/schema\/person\/4a0a717d05ab7bca77c74ce89ec295bf"},"breadcrumb":{"@id":"https:\/\/fireflyin.org\/resources\/news-library\/is-it-punishment-or-discipline\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fireflyin.org\/resources\/news-library\/is-it-punishment-or-discipline\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fireflyin.org\/resources\/news-library\/is-it-punishment-or-discipline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fireflyin.org\/"},{"@type":"ListItem","position":2,"name":"IS IT PUNISHMENT, OR DISCIPLINE?"}]},{"@type":"WebSite","@id":"https:\/\/fireflyin.org\/#website","url":"https:\/\/fireflyin.org\/","name":"Alliance des enfants et de la famille Firefly","description":"impact des parents d&#039;accueil, enfants en famille d&#039;accueil, parents d&#039;accueil n\u00e9cessaires, r\u00f4le d&#039;un parent d&#039;accueil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fireflyin.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/fireflyin.org\/#\/schema\/person\/4a0a717d05ab7bca77c74ce89ec295bf","name":"Alliance des enfants et de la famille Firefly","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/05d76712c41f02a8e2d8f22346b1a85e7f00cb4436efc2fa6670ee39129fd71b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05d76712c41f02a8e2d8f22346b1a85e7f00cb4436efc2fa6670ee39129fd71b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05d76712c41f02a8e2d8f22346b1a85e7f00cb4436efc2fa6670ee39129fd71b?s=96&d=mm&r=g","caption":"Firefly Children and Family Alliance"},"url":"https:\/\/fireflyin.org\/fr\/resources\/news-library\/author\/firefly-children-and-family-alliance\/"}]}},"_links":{"self":[{"href":"https:\/\/fireflyin.org\/fr\/wp-json\/wp\/v2\/posts\/10168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fireflyin.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fireflyin.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fireflyin.org\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/fireflyin.org\/fr\/wp-json\/wp\/v2\/comments?post=10168"}],"version-history":[{"count":0,"href":"https:\/\/fireflyin.org\/fr\/wp-json\/wp\/v2\/posts\/10168\/revisions"}],"wp:attachment":[{"href":"https:\/\/fireflyin.org\/fr\/wp-json\/wp\/v2\/media?parent=10168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fireflyin.org\/fr\/wp-json\/wp\/v2\/categories?post=10168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fireflyin.org\/fr\/wp-json\/wp\/v2\/tags?post=10168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}